{"id":886,"date":"2020-10-16T11:02:00","date_gmt":"2020-10-16T09:02:00","guid":{"rendered":"https:\/\/icc-weinfelden.ch\/?page_id=886"},"modified":"2020-10-16T11:02:00","modified_gmt":"2020-10-16T09:02:00","slug":"nuestros-pilares","status":"publish","type":"page","link":"https:\/\/icc-weinfelden.ch\/es\/nuestros-pilares\/","title":{"rendered":"Nuestros Pilares"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0%;--awb-padding-right:15%;--awb-padding-bottom:0%;--awb-padding-left:15%;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p align=\"center\"><b>Nuestros Pilares<\/b><\/p>\n<p align=\"center\"><b><i>Pilares Eclesi\u00e1sticos<\/i><\/b><\/p>\n<ul>\n<li>Centro de Adoraci\u00f3n a Dios: Nuestra iglesia motiva a sus miembros a vivir una vida que agrade a Dios en todos los lugares donde se muevan. Hace una diferencia entre la verdadera adoraci\u00f3n y la falsa (religiosidad)<\/li>\n<li>Centro de Revelaci\u00f3n de la gloria de Dios: Nuestra iglesia revela al mundo la gloria de Dios a trav\u00e9s de la transformaci\u00f3n de vidas que funciona como un im\u00e1n que atrae a otros.<\/li>\n<li>Centro de Demostraci\u00f3n del Poder de Dios: Es din\u00e1mica y efectiva por el poder de Dios sobre las enfermedades, la muerte, la naturaleza y los demonios.<\/li>\n<li>Centro de Expansi\u00f3n del Reino de Dios: Nuestra Iglesia busca activamente a su alrededor a quienes no son salvos y desarrolla programas de ense\u00f1anza para que puedan creer en Jesucristo y asuman la misi\u00f3n de ganar, edificar y enviar.<\/li>\n<\/ul>\n<p align=\"center\"><b><i>Pilares Organizacionales<\/i><\/b><\/p>\n<ul>\n<li>Unidad de Prop\u00f3sito: Todos los miembros de la empresa piensan y act\u00faan en consonancia con la Alta Direcci\u00f3n. Aunque exista autonom\u00eda y autosuficiencia en ciertas \u00e1reas de la organizaci\u00f3n, estas deben apuntar a un bien com\u00fan, a un mismo objetivo trazado por la Organizaci\u00f3n.<\/li>\n<li>Conocimiento del entorno: La Iglesia debe estar atenta a los cambios que ocurran a su alrededor en los \u00e1mbitos Pol\u00edticos, Legales, Econ\u00f3micos, Socio-culturales, Tecnol\u00f3gicos y Ecol\u00f3gicos con el fin de dar una respuesta oportuna.<\/li>\n<li>Liderazgo capaz: El l\u00edder es el centro en torno al que gravita la empresa. Si el l\u00edder es competente, la empresa prosperar\u00e1; si es incompetente, se crear\u00e1 caos.<\/li>\n<li>Organizaci\u00f3n Eficaz: La organizaci\u00f3n requiere sistemas de control adecuados, comunicaci\u00f3n fluida, asignaci\u00f3n eficaz de recursos y personal competente.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-886","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/pages\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":1,"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/pages\/886\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/pages\/886\/revisions\/889"}],"wp:attachment":[{"href":"https:\/\/icc-weinfelden.ch\/es\/wp-json\/wp\/v2\/media?parent=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}